{"id":8156,"date":"2017-11-22T09:25:39","date_gmt":"2017-11-22T14:25:39","guid":{"rendered":"https:\/\/wawa-news.com\/?p=8156"},"modified":"2019-05-29T06:49:20","modified_gmt":"2019-05-29T10:49:20","slug":"lacquisition-de-mines-richmont-par-alamos-gold-recoit-lapprobation-finale-de-la-cour","status":"publish","type":"post","link":"https:\/\/wawa-news.com\/index.php\/2017\/11\/22\/lacquisition-de-mines-richmont-par-alamos-gold-recoit-lapprobation-finale-de-la-cour\/","title":{"rendered":"L&#8217;acquisition de Mines Richmont par Alamos Gold re\u00e7oit l&#8217;approbation finale de la Cour"},"content":{"rendered":"<p><b>Nov 22, 2017 @ 09:25<\/b><\/p>\n<div class=\"clear\"><\/div><div class=\"divider\"><\/div>\n<div class=\"row\">\n<div class=\"col-sm-10 col-sm-offset-1\">\n<p>Alamos Gold Inc. et Mines Richmont inc. ont le plaisir d&#8217;annoncer que la Cour sup\u00e9rieure du Qu\u00e9bec (division commerciale) leur a accord\u00e9 l&#8217;approbation d\u00e9finitive du plan d&#8217;arrangement, selon lequel Alamos acquerra toutes les actions \u00e9mises et en circulation de Richmont.<\/p>\n<p>La Transaction devrait \u00eatre conclue le 23 novembre 2017, sous r\u00e9serve des approbations r\u00e9glementaires applicables et de la satisfaction des autres conditions habituelles.<\/p>\n<\/div>\n<\/div>\n<div class=\"row\"><\/div>\n<div class=\"row\">\n<div class=\"col-sm-10 col-sm-offset-1\">\n<p><b><u>\u00c0 propos d&#8217;Alamos Gold inc.<\/u><\/b><\/p>\n<p>Alamos est un producteur d&#8217;or interm\u00e9diaire bas\u00e9 au <span class=\"xn-location\">Canada<\/span> avec une production diversifi\u00e9e provenant de trois mines en exploitation en Am\u00e9rique du Nord, dont la <span class=\"xn-person\">Mine Young-Davidson<\/span> dans le nord de l&#8217;<span class=\"xn-location\">Ontario<\/span>au <span class=\"xn-location\">Canada<\/span> et les mines Mulatos et El Chanate dans l&#8217;\u00c9tat de <span class=\"xn-location\">Sonora<\/span>, au Mexique. De plus, la soci\u00e9t\u00e9 poss\u00e8de un important portefeuille de projets au stade de d\u00e9veloppement au <span class=\"xn-location\">Canada<\/span>, au Mexique, en Turquie et aux \u00c9tats-Unis. Alamos emploie plus de 1\u00a0300 personnes et s&#8217;engage \u00e0 respecter les normes de d\u00e9veloppement durable les plus \u00e9lev\u00e9es. Les actions de la soci\u00e9t\u00e9 sont inscrites \u00e0 la TSX et au NYSE sous le symbole \u00ab\u00a0AGI\u00a0\u00bb.<\/p>\n<p><b><u>\u00c0 propos de Mines Richmont inc.<\/u><\/b><\/p>\n<p>Actuellement, Mines Richmont produit de l&#8217;or \u00e0 partir de la mine Island Gold, en <span class=\"xn-location\">Ontario<\/span>, o\u00f9 elle progresse \u00e9galement avec le d\u00e9veloppement de l&#8217;extension de la ressource \u00e0 haute <span class=\"xn-money\">teneur<\/span> \u00e0 l&#8217;est et en profondeur. Avec plus de 35 ans d&#8217;exp\u00e9rience en exploration, d\u00e9veloppement et exploitation aurif\u00e8re et une excellente gestion financi\u00e8re, la soci\u00e9t\u00e9 a positionn\u00e9 avec succ\u00e8s la mine Island Gold afin d&#8217;accro\u00eetre, de fa\u00e7on rentable, son inventaire de r\u00e9serves au <span class=\"xn-location\">Canada<\/span> et d&#8217;entamer sa nouvelle phase de croissance. Les actions de la soci\u00e9t\u00e9 sont inscrites \u00e0 la TSX et au NYSE sous le symbole \u00ab\u00a0RIC\u00a0\u00bb.<\/p>\n<\/div>\n<\/div>\n<div class=\"grammarly-disable-indicator\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nov 22, 2017 @ 09:25 Alamos Gold Inc. et Mines Richmont inc. ont le plaisir d&#8217;annoncer que la Cour sup\u00e9rieure du Qu\u00e9bec (division commerciale) leur a accord\u00e9 l&#8217;approbation d\u00e9finitive du plan d&#8217;arrangement, selon lequel Alamos acquerra toutes les actions \u00e9mises et en circulation de Richmont. La Transaction devrait \u00eatre conclue le 23 novembre 2017, sous &#8230;<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[1009,563],"class_list":["post-8156","post","type-post","status-publish","format-standard","hentry","category-business","tag-alamos-gold","tag-richmond-mines"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:04:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/8156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/comments?post=8156"}],"version-history":[{"count":1,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/8156\/revisions"}],"predecessor-version":[{"id":8157,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/8156\/revisions\/8157"}],"wp:attachment":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media?parent=8156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/categories?post=8156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/tags?post=8156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}