{"id":66375,"date":"2024-04-08T08:00:29","date_gmt":"2024-04-08T12:00:29","guid":{"rendered":"https:\/\/wawa-news.com\/?p=66375"},"modified":"2024-04-06T07:19:47","modified_gmt":"2024-04-06T11:19:47","slug":"bien-que-le-taux-de-surdoses-et-de-deces-chez-les-habitants-du-nord-de-lontario-soit-le-triple-de-celui-du-reste-de-la-province-le-gouvernement-reste-impitoyablement-assis-sur-ses-mains","status":"publish","type":"post","link":"https:\/\/wawa-news.com\/index.php\/2024\/04\/08\/bien-que-le-taux-de-surdoses-et-de-deces-chez-les-habitants-du-nord-de-lontario-soit-le-triple-de-celui-du-reste-de-la-province-le-gouvernement-reste-impitoyablement-assis-sur-ses-mains\/","title":{"rendered":"Bien que le taux de surdoses et de d\u00e9c\u00e8s chez les habitants du Nord de  l\u2019Ontario soit le triple de celui du reste de la province, le gouvernement  reste impitoyablement assis sur ses mains"},"content":{"rendered":"<p><a href=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2023\/06\/Newsfromthepark-fr.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-61158\" src=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2023\/06\/Newsfromthepark-fr-300x200.png\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2023\/06\/Newsfromthepark-fr-300x200.png 300w, https:\/\/wawa-news.com\/wp-content\/uploads\/2023\/06\/Newsfromthepark-fr.png 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>La plupart des lecteurs ne seront pas surpris d\u2019entendre qu\u2019aucun d\u2019entre nous n\u2019est parfait. Il y en a qui peuvent penser et se comporter \u00e0 l\u2019effet contraire, mais je peux vous assurer qu\u2019une telle confiance en soi est mal plac\u00e9e. Pour toute personne de croire qu\u2019ils sont parfaits est, tout simplement, la preuve de leur sensibilit\u00e9 imparfaite.<\/p>\n<p>Aux yeux du Cr\u00e9ateur, tout le monde a de la valeur. Nous avons tous des difficult\u00e9s et des faiblesses. C\u2019est la nature humaine pour nous de vouloir nous \u00e9lever au-dessus. C\u2019est ce qu\u2019est la vie. Nous faisons face \u00e0 des d\u00e9fis et concevons des solutions \u00e0 r\u00e9soudre pour am\u00e9liorer et r\u00e9soudre nos probl\u00e8mes. Comment peut-on \u00e9valuer ou accorder une valeur plus \u00e9lev\u00e9e \u00e0 une personne qu\u2019\u00e0 une autre\u2009?<\/p>\n<p>Cependant, parfois, les gens doivent essayer et essayer \u00e0 nouveau de surmonter les faiblesses et les d\u00e9fis. Est-ce que tous les fumeurs conqui\u00e8rent leur d\u00e9pendance la premi\u00e8re fois\u2009? Les joueurs et les alcooliques s\u2019en sortent-ils mieux\u2009? Bien s\u00fbr que non. Les personnes confront\u00e9es \u00e0 de tels probl\u00e8mes devraient-elles \u00eatre mises de c\u00f4t\u00e9 ou oubli\u00e9es\u2009? Devrions-nous conclure que les citoyens imparfaits n\u2019ont aucune valeur ou but dans la soci\u00e9t\u00e9 et sont condamn\u00e9s\u2009? En faisant un pas \u00e0 la fois, les gens retournent leur vie pour le mieux chaque jour.<\/p>\n<p>Trop de personnes souffrant de d\u00e9pendances et sont oblig\u00e9es d\u2019obtenir leur dose dans l\u2019isolement, ce qui est une pratique dangereuse. Il y a une autre fa\u00e7on. Pour faire face aux dangers li\u00e9s \u00e0 la consommation de substances illicites, notre syst\u00e8me de sant\u00e9 publique comprend des sites de consommation s\u00e9curitaires et supervis\u00e9s afin que les personnes en pleine lutte contre la d\u00e9pendance n\u2019aient pas \u00e0 risquer de se blesser et de mourir \u00e0 cause d\u2019un approvisionnement empoisonn\u00e9, d\u2019une dose l\u00e9tale ou d\u2019\u00e9quipement contamin\u00e9. Il y a un personnel de soutien form\u00e9 sur place au cas o\u00f9 les choses tourneraient mal, comme des surdoses ou des m\u00e9dicaments toxiques. De plus, le personnel est pr\u00eat \u00e0 offrir de l\u2019information et du soutien \u00e0 ceux qui d\u00e9cident qu\u2019il est temps de ma\u00eetriser leur d\u00e9pendance. Cette approche d\u00e9coule de la philosophie selon laquelle une personne ayant une d\u00e9pendance de quelque nature que ce soit peut changer son comportement et recommencer \u00e0 z\u00e9ro.<\/p>\n<p>Tous les gens ont de la valeur et m\u00e9ritent de vivre. Nous sommes tous l\u2019enfant, le fr\u00e8re ou la s\u0153ur, le parent ou l\u2019ami de quelqu\u2019un. La chose humaine que nous devons faire est de tendre la main pour aider les autres quand ils ont besoin de soutien. Et c\u2019est ce que font les sites de consommation s\u00e9curitaires. Mieux encore, ils sauvent efficacement des vies et offrent de nombreux autres avantages. Sant\u00e9 Canada \u00e9num\u00e8re les avantages suivants de la prestation de sites de consommation supervis\u00e9e\u00a0:<\/p>\n<ul>\n<li>r\u00e9duire le risque de surdose accidentelle parce que les gens ne se pr\u00e9cipitent pas ou n\u2019utilisent pas seuls<\/li>\n<li>mettre les gens en contact avec des services sociaux comme le logement, l\u2019aide \u00e0 l\u2019emploi et les banques alimentaires<\/li>\n<li>fournir ou connecter les gens aux soins de sant\u00e9 et aux traitements,<\/li>\n<li>r\u00e9duire la consommation publique de drogues et le mat\u00e9riel de drogue mis au rebut<\/li>\n<li>r\u00e9duire la propagation de maladies infectieuses, comme le VIH<\/li>\n<li>r\u00e9duire la pression sur les services m\u00e9dicaux d\u2019urgence, afin qu\u2019ils puissent se concentrer sur d\u2019autres urgences<\/li>\n<li>offre aux gens un espace pour entrer en contact avec le personnel et les pairs, ce qui peut aider une personne \u00e0 mod\u00e9rer sa consommation de drogues et \u00e0 d\u00e9cider de poursuivre un traitement.<\/li>\n<li>Regardez les statistiques publi\u00e9es par Algoma Public Health (APH). Les taux de mortalit\u00e9 li\u00e9e aux opio\u00efdes dans les collectivit\u00e9s du Nord de l\u2019Ontario sont TROIS FOIS plus \u00e9lev\u00e9s que la moyenne provinciale. Ce sont des niveaux de crise\u2009!<\/li>\n<\/ul>\n<p>Apr\u00e8s l\u2019\u00e9lection du gouvernement Ford en 2018, consult\u00e9e sur la n\u00e9cessit\u00e9 de sites de consommation plus s\u00e9curitaires, la ministre de la Sant\u00e9, Christine Elliott, a annonc\u00e9 en juillet que la province commencerait \u00e0 examiner le bien-fond\u00e9 d\u2019un tel financement. Eh bien, nous sommes en avril 2024, et le Minist\u00e8re n\u2019a pas encore termin\u00e9 ses d\u00e9lib\u00e9rations. Le num\u00e9ro du 13\u00a0mars 2024 du Sault Star indiquait que le premier ministre avait d\u00e9clar\u00e9 que l\u2019examen \u00e9tait \u00ab\u2009presque termin\u00e9\u2009\u00bb.<\/p>\n<p>Le manque d\u2019urgence du gouvernement Ford \u00e0 r\u00e9soudre ce probl\u00e8me ici dans le Nord, dont les conservateurs de Ford font preuve, est \u00e9pouvantable. Ne croient-ils pas que toutes les vies, y compris celles des habitants du Nord de l\u2019Ontario, ont de la valeur\u2009? Qu\u2019est-ce que le retard\u2009?<\/p>\n<p>Le 5\u00a0mars 2024, CBC News a rapport\u00e9 que des groupes communautaires de l\u2019Ontario ont suppli\u00e9 le gouvernement provincial de financer et de soutenir imm\u00e9diatement les services de consommation supervis\u00e9e, y compris nos communaut\u00e9s du Nord. De plus, la Coalition canadienne des politiques sur les drogues a \u00e9crit une lettre ouverte au gouvernement de l\u2019Ontario le 5\u00a0mars 2024. La lettre contenait huit appels \u00e0 l\u2019action du gouvernement et demandait une r\u00e9union dans les jours suivants en raison de la nature urgente de la situation. Les infirmi\u00e8res et infirmiers autoris\u00e9s de l\u2019Ontario ont \u00e9galement \u00e9mis une alerte d\u2019action demandant aux gens de dire au premier ministre Ford de lever sa gel\u00e9e des approbations de sites s\u00fbrs. Et f\u00e9licitations au maire Matthew Shoemaker de Sault Ste. Marie qui a \u00e9crit dix lettres au gouvernement au sujet du manque d\u2019investissement dans les projets de sant\u00e9 mentale et de toxicomanie, y compris les sites de consommation s\u00e9curitaire, ici dans le Nord.<\/p>\n<p>Comment le premier ministre Ford peut-il justifier le maintien d\u2019un plaf\u2009?<\/p>\n<p>ond de sites de consommation financ\u00e9s en Ontario \u00e0 seulement 21\u2009? Et sachant \u00e0 quel point les sites de consommation s\u00fbrs sont efficaces, comment peut-il justifier de prendre autant de temps \u00e0 consid\u00e9rer s\u2019il s\u2019agit d\u2019un investissement rentable\u2009? Ce qui rend cela si impitoyable, c\u2019est que les souffrances et les d\u00e9c\u00e8s sont \u00e9vitables. Le premier ministre croit-il que la vie des personnes aux probl\u00e8mes de toxicomanie a moins de valeur\u2009? Et n\u2019oubliez pas comment le premier ministre Ford pr\u00e9tend toujours qu\u2019il est l\u00e0 pour les petits gars.<\/p>\n<p>Le gouvernement reste assis sur ses mains depuis trop longtemps. En fait, il \u00e9tudie la question depuis l\u2019arriv\u00e9e au pouvoir des conservateurs. Il ne s\u2019agit pas seulement d\u2019un document de fin de trimestre d\u2019\u00e9tudes secondaires. C\u2019est litt\u00e9ralement une question de vie ou de mort.<\/p>\n<p>Si nous voulons que le monde soit meilleur, nous devons apprendre \u00e0 aimer ou au moins \u00e0 prendre soin de tout le monde. Prendre soin des autres n\u2019est que la nature humaine, et cela donne \u00e0 notre vie un but au-del\u00e0 de notre \u00e9panouissement. C\u2019est ce pour quoi les gouvernements sont \u00e9lus\u00a0: prot\u00e9ger et prendre soin de tous sur un pied d\u2019\u00e9galit\u00e9. Je vais vous laisser avec cette citation de l\u2019auteur Nate Sanna\u00a0: \u00ab\u2009Notre amour est un jardin, et l\u00e0 o\u00f9 il y a une d\u00e9pendance, les mauvaises herbes poussent. Mais je suis le cultivateur\u2009; je continuerai \u00e0 m\u2019occuper des fleurs de notre amour, en attendant que vous vous joigniez \u00e0 moi pour sentir les fleurs.<\/p>\n<p>Comme toujours, je vous invite \u00e0 communiquer avec mon bureau au sujet de ces questions ou de toute autre question provinciale. Vous pouvez joindre mon bureau de circonscription par courriel \u00e0 mmantha-co@ola.org ou appeler sans frais le 1-800-831-1899.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La plupart des lecteurs ne seront pas surpris d\u2019entendre qu\u2019aucun d\u2019entre nous n\u2019est parfait. Il y en a qui peuvent penser et se comporter \u00e0 l\u2019effet contraire, mais je peux vous assurer qu\u2019une telle confiance en soi est mal plac\u00e9e. Pour toute personne de croire qu\u2019ils sont parfaits est, tout simplement, la preuve de leur &#8230;<\/p>\n","protected":false},"author":57,"featured_media":61158,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-66375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-community"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:59:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/66375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/comments?post=66375"}],"version-history":[{"count":2,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/66375\/revisions"}],"predecessor-version":[{"id":66377,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/66375\/revisions\/66377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media\/61158"}],"wp:attachment":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media?parent=66375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/categories?post=66375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/tags?post=66375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}