{"id":65232,"date":"2024-02-13T14:24:36","date_gmt":"2024-02-13T19:24:36","guid":{"rendered":"https:\/\/wawa-news.com\/?p=65232"},"modified":"2024-02-13T14:25:16","modified_gmt":"2024-02-13T19:25:16","slug":"lontario-protege-la-population-contre-les-couts-eleves-dune-taxe-provinciale-sur-le-carbone","status":"publish","type":"post","link":"https:\/\/wawa-news.com\/index.php\/2024\/02\/13\/lontario-protege-la-population-contre-les-couts-eleves-dune-taxe-provinciale-sur-le-carbone\/","title":{"rendered":"L\u2019Ontario prot\u00e8ge la population contre les co\u00fbts \u00e9lev\u00e9s d\u2019une taxe provinciale sur le carbone"},"content":{"rendered":"<p><a href=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2020\/07\/trillium-1-e1706704249666.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-33734\" src=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2020\/07\/trillium-1-e1706704249666.png\" alt=\"\" width=\"300\" height=\"274\" \/><\/a>Le gouvernement de l\u2019Ontario s\u2019efforce de r\u00e9duire les co\u00fbts pour la population en pr\u00e9sentant un projet de loi qui, s\u2019il est adopt\u00e9, donnerait aux \u00e9lecteurs de la province un droit de regard sur la mise en place \u00e9ventuelle d\u2019une nouvelle taxe provinciale sur le carbone, d\u2019un syst\u00e8me de plafonnement et d\u2019\u00e9change ou de tout autre programme de tarification du carbone. Ce projet de loi prot\u00e9gerait les citoyens ainsi que les entreprises contre le co\u00fbt \u00e9lev\u00e9 d\u2019une taxe provinciale sur le carbone en exigeant le consentement des \u00e9lecteurs de l\u2019Ontario par le biais d\u2019un r\u00e9f\u00e9rendum avant la mise en \u0153uvre d\u2019un nouveau programme provincial de tarification du carbone.<br \/>\n\u00ab Avec les taux d\u2019int\u00e9r\u00eat \u00e9lev\u00e9s de la Banque du Canada et le co\u00fbt de la vie qui reste tr\u00e8s \u00e9lev\u00e9, il n\u2019a jamais \u00e9t\u00e9 aussi important de r\u00e9duire les co\u00fbts pour les particuliers et les entreprises, a d\u00e9clar\u00e9 le premier ministre Doug Ford. J\u2019ai toujours dit que la taxe sur le carbone est la pire des taxes. Elle fait augmenter le co\u00fbt de tout. Nous devons prot\u00e9ger les travailleurs et les familles de l\u2019Ontario contre le co\u00fbt \u00e9lev\u00e9 de la taxe sur le carbone et nous exhortons le gouvernement f\u00e9d\u00e9ral \u00e0 faire de m\u00eame. \u00bb<\/p>\n<p>Le gouvernement de l\u2019Ontario continue de prier le gouvernement f\u00e9d\u00e9ral d\u2019appliquer au chauffage domestique la m\u00eame d\u00e9rogation que celle accord\u00e9e aux provinces de l\u2019Atlantique ou d\u2019\u00e9liminer compl\u00e8tement la taxe f\u00e9d\u00e9rale sur le carbone.<\/p>\n<p>\u00ab Nous avons promis de lutter contre la taxe f\u00e9d\u00e9rale sur le carbone et notre gouvernement continuera \u00e0 montrer l\u2019exemple, en assurant aux Ontariens et Ontariennes que nous n\u2019irons pas de l\u2019avant en imposant une taxe sur le carbone au d\u00e9triment des contribuables, a d\u00e9clar\u00e9 Peter Bethlenfalvy, ministre des Finances. Toute nouvelle taxe provinciale sur le carbone est inacceptable pour la population de l\u2019Ontario, qui voit l\u2019argent qu\u2019elle a durement gagn\u00e9 d\u00e9pens\u00e9 comme jamais auparavant. \u00bb<\/p>\n<p>Cette mesure fait partie d\u2019un projet de loi qui donnera le coup d\u2019envoi de la s\u00e9ance l\u00e9gislative du printemps, le 20 f\u00e9vrier 2024. La Loi de 2024 pour passer \u00e0 l\u2019action comprendra une s\u00e9rie de mesures qui, si elles sont adopt\u00e9es, s\u2019appuieront sur les engagements pris jusqu\u2019\u00e0 pr\u00e9sent par le gouvernement pour simplifier l\u2019approbation des projets importants de construction d\u2019infrastructure et de logements, r\u00e9duire les co\u00fbts pour les particuliers et les entreprises et soutenir la croissance \u00e9conomique en vue d\u2019une prosp\u00e9rit\u00e9 \u00e0 long terme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le gouvernement de l\u2019Ontario s\u2019efforce de r\u00e9duire les co\u00fbts pour la population en pr\u00e9sentant un projet de loi qui, s\u2019il est adopt\u00e9, donnerait aux \u00e9lecteurs de la province un droit de regard sur la mise en place \u00e9ventuelle d\u2019une nouvelle taxe provinciale sur le carbone, d\u2019un syst\u00e8me de plafonnement et d\u2019\u00e9change ou de tout autre &#8230;<\/p>\n","protected":false},"author":46,"featured_media":31649,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-65232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-community"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:03:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/65232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/comments?post=65232"}],"version-history":[{"count":1,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/65232\/revisions"}],"predecessor-version":[{"id":65233,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/65232\/revisions\/65233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media\/31649"}],"wp:attachment":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media?parent=65232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/categories?post=65232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/tags?post=65232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}