{"id":62985,"date":"2023-10-16T08:00:27","date_gmt":"2023-10-16T12:00:27","guid":{"rendered":"https:\/\/wawa-news.com\/?p=62985"},"modified":"2023-10-16T06:03:43","modified_gmt":"2023-10-16T10:03:43","slug":"le-theatre-des-soins-de-sante-de-ford","status":"publish","type":"post","link":"https:\/\/wawa-news.com\/index.php\/2023\/10\/16\/le-theatre-des-soins-de-sante-de-ford\/","title":{"rendered":"Le th\u00e9\u00e2tre des soins de sant\u00e9 de Ford"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-61158\" src=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2023\/06\/Newsfromthepark-fr-300x200.png\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2023\/06\/Newsfromthepark-fr-300x200.png 300w, https:\/\/wawa-news.com\/wp-content\/uploads\/2023\/06\/Newsfromthepark-fr.png 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>J\u2019ose dire que de nombreux Ontariens sont boulevers\u00e9s et d\u00e9\u00e7us par les nombreux scandales \u00e9manant du gouvernement Ford ces derniers temps.<\/p>\n<p>Pr\u00e9sentement, nous observons les sagas de l\u2019ensemble r\u00e9sidentiel et la ceinture de verdure. Nous venons d\u2019\u00eatre t\u00e9moins de la virevolte du premier ministre sur la restitution des terres de la Ceinture de verdure, la d\u00e9mission r\u00e9cente de deux ministres \u00e9minents du Cabinet et la d\u00e9mission d\u2019un membre du personnel du minist\u00e8re. Parlez d\u2019une mauvaise r\u00e9putation.<\/p>\n<p>Vous n\u2019avez pas \u00e0 parcourir loin pour trouver des scandales, des promesses non tenues et des essais du gouvernement de d\u00e9tourner l\u2019attention du public. Par exemple, pour distraire les Ontariens du scandale de la ceinture de verdure, le premier ministre Ford a fait des commentaires impolis au sujet des conseils scolaires qui travaillent avec des \u00e9l\u00e8ves sur les questions LGBTQ concernant les pronoms. Vraiment, monsieur Ford\u00a0? Les conseils scolaires endoctrinent les enfants\u00a0? C\u2019est une tactique typique de Doug Ford.<\/p>\n<p>Pour moi, les soins de sant\u00e9 sont le seul domaine qui nous affectera tous personnellement \u00e0 un moment donn\u00e9. C\u2019est une pr\u00e9occupation majeure pour les Ontariennes et Ontariens. Au mieux, les tentatives du gouvernement Ford d&#8217;am\u00e9liorer les soins de sant\u00e9 ont \u00e9t\u00e9 <em>feintes<\/em> ou \u00e0 peine masqu\u00e9s.<\/p>\n<p>Vous remarquerez que je dis <em>tentatives feintes<\/em> . Je ne peux pas m\u2019emp\u00eacher de penser \u00e0 un sketch comique dans lequel un homme g\u00e9ant et muscl\u00e9 prit toutes ses forces pour soulever une barre de 800 livres, seulement pour avoir un vieil homme grincheux nettoyer la sc\u00e8ne apr\u00e8s le spectacle et porter l\u2019halt\u00e8re dans une main. Ce n\u2019est qu\u2019une autre tactique du premier ministre Ford qui s\u2019est d\u00e9roul\u00e9e de fa\u00e7on th\u00e9\u00e2trale avec ses ministres de la Sant\u00e9. En entendant Doug Ford parler, on peut penser qu\u2019il essayait de pousser un rocher sur un flanc de montagne, son visage grima\u00e7ant alors qu\u2019il parle aux m\u00e9dias de leurs incroyables am\u00e9liorations. Leurs efforts robustes ne sont pas plus authentiques que les halt\u00e9rophiles.<\/p>\n<p>\u00c0 maintes reprises, le premier ministre Ford a promis aux Ontariennes et aux Ontariens qu\u2019il faisait tout ce qui est humainement possible pour r\u00e9parer les soins de sant\u00e9. Il affirme que le probl\u00e8me n\u2019est pas un manque d\u2019argent, mais plut\u00f4t que le financement doit \u00eatre r\u00e9affect\u00e9 aux premi\u00e8res lignes.<\/p>\n<p>Eh bien, je peux comprendre pourquoi il dit r\u00e9affecter l\u2019argent aux premi\u00e8res lignes. C\u2019est parce que ce sont les lignes de front que le gouvernement se fait attaquer\u00a0! Les m\u00e9decins et les infirmi\u00e8res ont l\u2019air \u00e9puiser et les yeux sombres dans l\u2019\u0153il du public et des m\u00e9dias. Les gens voient et entendent des patients confin\u00e9s dans les couloirs, les salles d\u2019entreposage et m\u00eame quelques toilettes. Mais, l\u2019argent n\u00e9cessaire en arri\u00e8re-plan n\u2019est pas exactement exc\u00e9dentaire. Il est n\u00e9cessaire pour l\u2019\u00e9quipement et le traitement de fournir suffisamment de personnel que les m\u00e9decins et les infirmi\u00e8res n\u2019ont pas \u00e0 porter des patins \u00e0 roulettes pour se d\u00e9placer. Tout ce que le premier ministre fait, c\u2019est r\u00e9affecter l\u2019argent, pas le remplacer.<\/p>\n<p>Le mois dernier, <strong><em>Global News<\/em><\/strong> a publi\u00e9 une s\u00e9rie approfondie sur les lettres de mandat du minist\u00e8re que le premier ministre Ford a envoy\u00e9es \u00e0 chaque ministre pour exposer les plans du gouvernement apr\u00e8s les derni\u00e8res \u00e9lections. Dans sa lettre au ministre de la Sant\u00e9 et des Soins de longue dur\u00e9e, M. Ford a \u00e9crit : \u00ab Revoir la structure de surveillance des soins de sant\u00e9 du minist\u00e8re de la Sant\u00e9 et des soins de longue dur\u00e9e et de ses organismes afin de cr\u00e9er un syst\u00e8me de soins de sant\u00e9 ax\u00e9 sur le patient et la famille. \u00bb<\/p>\n<p><em>Le journaliste \u00a0<\/em>a ajout\u00e9 que \u00ab tout au long de la lettre de mandat adress\u00e9e au ministre de la Sant\u00e9 est un th\u00e8me r\u00e9current qui consiste \u00e0 trouver des \u00e9conomies et des gains d&#8217;efficience, dans la mesure du possible, et \u00e0 r\u00e9investir l&#8217;argent dans les premi\u00e8res lignes \u00bb. Le premier ministre leur a demand\u00e9 de recr\u00e9er un syst\u00e8me de soins de sant\u00e9 \u00ab efficace, ax\u00e9 sur le patient, \u00e0 la fine pointe de la technologie et de classe mondiale \u00bb. M. Ford, vous ne pouvez pas avoir le v\u00f4tre g\u00e2teux et manger votre g\u00e2teux.<\/p>\n<p>Je dois demander au premier ministre comment il fait une telle magie lorsque le Bureau de la responsabilit\u00e9 financi\u00e8re a signal\u00e9 que le gouvernement a d\u00e9pens\u00e9 7 milliards de dollars de moins que pr\u00e9vu cette ann\u00e9e, avec 1,6 milliard de dollars de moins dans les soins de sant\u00e9 seulement.<\/p>\n<p>Ici, dans le nord, les gens essaient fr\u00e9n\u00e9tiquement de trouver un m\u00e9decin de famille pr\u00eat \u00e0 les ajouter \u00e0 leur liste. Il ne se passe pas une semaine sans que quelqu&#8217;un appelle ou \u00e9crive \u00e0 notre bureau, suppliant mon bureau de les aider \u00e0 trouver un m\u00e9decin. Les chiffres actuels montrent qu&#8217;un r\u00e9sident du nord sur huit n&#8217;a pas acc\u00e8s \u00e0 un m\u00e9decin de famille. Pour aggraver le probl\u00e8me, l&#8217;\u00e2ge moyen des m\u00e9decins de famille qui exercent au Canada est de 49 ans. La retraite est \u00e0 l&#8217;horizon pour beaucoup. Combien de fois les r\u00e9sidants du nord ont-ils entendu le premier ministre et le ministre de la Sant\u00e9 chanter leur duo sur la fa\u00e7on dont ils travaillent dur pour r\u00e9soudre le probl\u00e8me et qu&#8217;ils n&#8217;\u00e9pargnent aucune d\u00e9pense pour former plus de m\u00e9decins et les amener \u00e0 rester et \u00e0 travailler dans le nord\u00a0?<\/p>\n<p>Pour r\u00e9soudre le probl\u00e8me, le gouvernement doit s&#8217;engager de fa\u00e7on permanente \u00e0 augmenter de 4 millions de dollars le financement de base pour former de nouveaux m\u00e9decins \u00e0 l<em>&#8216;\u00c9cole de m\u00e9decine du nord de l&#8217;Ontario<\/em>.<\/p>\n<p>Personnellement, j&#8217;aime le bon th\u00e9\u00e2tre, mais la loi du gouvernement Ford vieillit. Je trouve tout simplement exasp\u00e9rant de voir et d&#8217;entendre la th\u00e9\u00e2tralit\u00e9 du premier ministre Ford et de ses ministres de la Sant\u00e9 alors qu&#8217;ils essaient de nous convaincre tous que rien n&#8217;est plus important pour eux que la sant\u00e9 de tous les citoyens. Mais il semble que le spectacle ne se termine jamais. Notre syst\u00e8me de sant\u00e9 est en proie \u00e0 la privatisation, et les souffrances des gens ne feront qu&#8217;empirer.<\/p>\n<p>Comme toujours, n&#8217;h\u00e9sitez pas \u00e0 communiquer avec mon bureau au sujet de ces questions ou de toute autre question provinciale. Vous pouvez joindre mon bureau de circonscription par courriel \u00e0 <strong>mmantha-co@ola.org<\/strong> ou par t\u00e9l\u00e9phone sans frais au 1-800-831-1899.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u2019ose dire que de nombreux Ontariens sont boulevers\u00e9s et d\u00e9\u00e7us par les nombreux scandales \u00e9manant du gouvernement Ford ces derniers temps. Pr\u00e9sentement, nous observons les sagas de l\u2019ensemble r\u00e9sidentiel et la ceinture de verdure. Nous venons d\u2019\u00eatre t\u00e9moins de la virevolte du premier ministre sur la restitution des terres de la Ceinture de verdure, la &#8230;<\/p>\n","protected":false},"author":57,"featured_media":61158,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[],"class_list":["post-62985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-community"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 14:02:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/62985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/comments?post=62985"}],"version-history":[{"count":1,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/62985\/revisions"}],"predecessor-version":[{"id":62986,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/62985\/revisions\/62986"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media\/61158"}],"wp:attachment":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media?parent=62985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/categories?post=62985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/tags?post=62985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}