{"id":6270,"date":"2017-09-12T08:53:52","date_gmt":"2017-09-12T12:53:52","guid":{"rendered":"http:\/\/wawa-news.com\/?p=6270"},"modified":"2020-08-24T13:34:12","modified_gmt":"2020-08-24T17:34:12","slug":"la-vente-de-biens-publics-noffre-pas-davantages-a-long-terme","status":"publish","type":"post","link":"https:\/\/wawa-news.com\/index.php\/2017\/09\/12\/la-vente-de-biens-publics-noffre-pas-davantages-a-long-terme\/","title":{"rendered":"La vente de biens publics n\u2019offre pas d\u2019avantages \u00e0 long terme"},"content":{"rendered":"<p><a href=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2017\/02\/CarolHughes.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-1093\" src=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2017\/02\/CarolHughes-280x300.png\" alt=\"\" width=\"280\" height=\"300\" srcset=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2017\/02\/CarolHughes-280x300.png 280w, https:\/\/wawa-news.com\/wp-content\/uploads\/2017\/02\/CarolHughes.png 520w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/><\/a>Plus les Canadiens examinent l\u2019engagement des lib\u00e9raux d\u2019investir dans l\u2019infrastructure publique, plus ils se rendent \u00e0 l\u2019\u00e9vidence que le plan lib\u00e9ral consiste principalement \u00e0 transf\u00e9rer de l\u2019argent des contribuables et des biens publics au secteur priv\u00e9. Il n\u2019a jamais \u00e9t\u00e9 question de ce mod\u00e8le d\u2019investissement \u00e0 but lucratif pendant la campagne \u00e9lectorale, vraisemblablement parce qu\u2019il n\u2019aurait jamais obtenu beaucoup d\u2019appuis au sein de la population. La cr\u00e9ation de la banque de l\u2019infrastructure qui vise \u00e0 fournir des deniers publics \u00e0 des investisseurs priv\u00e9s a mis au jour l\u2019intention du gouvernement d\u2019appuyer des projets \u00e0 but lucratif et de vendre des biens publics.<\/p>\n<p>Dans une certaine mesure, ce n\u2019est pas du nouveau. Cependant, une nouvelle donn\u00e9e n\u2019a pas attir\u00e9 suffisamment d\u2019attention pendant l\u2019\u00e9t\u00e9. Nombre de personnes se rappelleront que la vente de biens publics figurait parmi les principaux th\u00e8mes du d\u00e9bat sur le budget. On a notamment appris que le gouvernement a retenu les services de la soci\u00e9t\u00e9 d\u2019experts-conseils PricewaterhouseCoopers pour savoir comment proc\u00e9der \u00e0 une \u00e9ventuelle privatisation des a\u00e9roports canadiens. Cet \u00e9t\u00e9, un site Web du gouvernement, en l\u2019occurrence Buyandsell.gc.ca, a r\u00e9v\u00e9l\u00e9 que les lib\u00e9raux envisagent de vendre jusqu\u2019\u00e0 concurrence de 8,3\u00a0milliards de dollars de l\u2019infrastructure de Parcs Canada. Ce projet de cession vise des routes, des ponts et des barrages essentiels pour nos parcs nationaux. Or, la vente de ces importants \u00e9l\u00e9ments d\u2019infrastructure permettrait \u00e0 des investisseurs priv\u00e9s d\u2019engranger des profits aux d\u00e9pens des g\u00e9n\u00e9rations futures et risquerait de limiter l\u2019acc\u00e8s aux parcs nationaux.<\/p>\n<p>Les Canadiens sont attach\u00e9s \u00e0 leurs parcs nationaux, comme le gouvernement le sait pertinemment. Ces espaces naturels figurent au nombre des \u00e9l\u00e9ments importants \u00e9nonc\u00e9s dans la lettre de mandat remise \u00e0 la ministre de l\u2019Environnement et du Changement climatique. Ce document souligne notamment la n\u00e9cessit\u00e9 de prot\u00e9ger le r\u00e9seau des parcs nationaux et de mieux servir les Canadiens de toutes les couches de la soci\u00e9t\u00e9. Qui plus est, dans le cadre des c\u00e9l\u00e9brations du 150e\u00a0anniversaire du Canada, le gouvernement offre cette ann\u00e9e l\u2019acc\u00e8s gratuit aux parcs nationaux. Toutefois, alors m\u00eame qu\u2019un nombre record de personnes visitent nos parcs nationaux, le gouvernement envisage la vente d\u2019\u00e9l\u00e9ments d\u2019infrastructure essentiels. Or, la concr\u00e9tisation de ce projet limiterait l\u2019acc\u00e8s aux territoires des parcs et entra\u00eenerait dans l\u2019avenir une augmentation des co\u00fbts pour les Canadiens. Il importe de signaler qu\u2019aucune de ces cons\u00e9quences ne correspond aux objectifs \u00e9nonc\u00e9s dans la lettre de mandat que le premier ministre a fait parvenir \u00e0 la ministre.<\/p>\n<p>Les n\u00e9o-d\u00e9mocrates craignent que le gouvernement n\u2019ait renonc\u00e9 \u00e0 sa promesse de prot\u00e9ger les parcs nationaux. Plut\u00f4t que d\u2019\u00e9couter les personnes qui connaissent bien ces espaces naturels et qui r\u00e9clament un meilleur entretien de leur infrastructure, le gouvernement engage Parcs Canada sur une voie erron\u00e9e et irresponsable. Par surcro\u00eet, comme rien n\u2019indique que des consultations publiques sont pr\u00e9vues dans le processus, il y a tout lieu de croire que le gouvernement n\u2019amorce des discussions avec le secteur priv\u00e9 avant m\u00eame de mener des consultations aupr\u00e8s des Canadiens.<\/p>\n<p>\u00c0 d\u00e9faut de consultations, la vente de biens de Parcs Canada pourrait donner l\u2019impression que le gouvernement favorise ses partisans. Bon nombre d\u2019intervenants doivent participer \u00e0 toutes les n\u00e9gociations susceptibles d\u2019entra\u00eener des changements consid\u00e9rables \u00e0 nos parcs nationaux. Les intervenants communautaires, les environnementalistes, les Premi\u00e8res Nations locales et les Canadiens qui fr\u00e9quentent les parcs doivent \u00eatre consult\u00e9s en bonne et due forme afin que le gouvernement comprenne pleinement l\u2019incidence que risque d\u2019avoir la privatisation des \u00e9l\u00e9ments d\u2019infrastructure vis\u00e9s. L\u2019enjeu ne se limite pas \u00e0 une entr\u00e9e d\u2019argent ponctuelle et les Canadiens m\u00e9ritent que le gouvernement pr\u00eate oreille \u00e0 leurs pr\u00e9occupations avant qu\u2019il ne soit trop tard pour y r\u00e9agir.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plus les Canadiens examinent l\u2019engagement des lib\u00e9raux d\u2019investir dans l\u2019infrastructure publique, plus ils se rendent \u00e0 l\u2019\u00e9vidence que le plan lib\u00e9ral consiste principalement \u00e0 transf\u00e9rer de l\u2019argent des contribuables et des biens publics au secteur priv\u00e9. Il n\u2019a jamais \u00e9t\u00e9 question de ce mod\u00e8le d\u2019investissement \u00e0 but lucratif pendant la campagne \u00e9lectorale, vraisemblablement parce qu\u2019il &#8230;<\/p>\n","protected":false},"author":11,"featured_media":1093,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,216,85],"tags":[349],"class_list":["post-6270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-community","category-editorials","category-politics","tag-carol-hughes"],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 01:37:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/6270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/comments?post=6270"}],"version-history":[{"count":1,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/6270\/revisions"}],"predecessor-version":[{"id":6272,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/6270\/revisions\/6272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media\/1093"}],"wp:attachment":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media?parent=6270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/categories?post=6270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/tags?post=6270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}