{"id":58372,"date":"2023-01-09T07:00:40","date_gmt":"2023-01-09T12:00:40","guid":{"rendered":"https:\/\/wawa-news.com\/?p=58372"},"modified":"2023-01-09T07:51:27","modified_gmt":"2023-01-09T12:51:27","slug":"secfdc-membre-du-conseil-dadministration","status":"publish","type":"post","link":"https:\/\/wawa-news.com\/index.php\/2023\/01\/09\/secfdc-membre-du-conseil-dadministration\/","title":{"rendered":"SECFDC &#8211; membre du conseil d\u2019administration"},"content":{"rendered":"<p><strong>La Soci\u00e9t\u00e9 d\u2019aide au d\u00e9veloppement des collectivit\u00e9s Sup\u00e9rieur Est<\/strong><br \/>\n<strong>cherche membre du conseil d\u2019administration<\/strong><\/p>\n<p>La Soci\u00e9t\u00e9 d\u2019aide au d\u00e9veloppement des collectivit\u00e9s du Sup\u00e9rieur Est (SADCSE) a des postes \u00e0 combler sur son conseil d\u2019administration pour la r\u00e9gion de Wawa. La SADC est une soci\u00e9t\u00e9 \u00e0 but non-lucratif offrant des services r\u00e9gionaux de d\u00e9veloppement \u00e9conomique et d\u2019entreprises pour la r\u00e9gion Sup\u00e9rieur Est, englobant Wawa, Chapleau, White River et Dubreuilville ainsi que les Premi\u00e8res Nations.<\/p>\n<p>Des b\u00e9n\u00e9voles en provenance de chaque communaut\u00e9 assument toutes les questions touchant l\u2019exploitation, les placements, la planification et les politiques de la soci\u00e9t\u00e9. Si vous aimeriez offrir votre temps et votre enthousiasme \u00e0 cet organisme, il nous ferait plaisir de vous consid\u00e9rer comme candidat. Les nouveaux membres re\u00e7oivent une trousse d\u2019orientation pour faciliter leur int\u00e9gration au sein du conseil d\u2019administration. Le candidat id\u00e9al devrait poss\u00e9der les atouts suivants :<\/p>\n<ul>\n<li>avoir d\u00e9j\u00e0 si\u00e9g\u00e9 sur d\u2019autres conseils d\u2019administration<\/li>\n<li>\u00eatre dispos\u00e9 \u00e0 voyager<\/li>\n<li>poss\u00e9der une connaissance de base des petites entreprises<\/li>\n<li>d\u00e9sirer ardemment que sa communaut\u00e9 b\u00e9n\u00e9ficie des services de la SADC<\/li>\n<li>avoir la capacit\u00e9 de travailler conjointement avec les membres des autres collectivit\u00e9s et poss\u00e9der une optique r\u00e9gionale<\/li>\n<li>avoir suffisamment de temps \u00e0 consacrer aux fins de r\u00e9vision et de consid\u00e9ration des affaires de la Soci\u00e9t\u00e9 sur une base mensuelle<\/li>\n<\/ul>\n<p>Sup\u00e9rieur Est s\u2019engage envers la diversit\u00e9 au sein de l\u2019organisation et encourage les demandes de toutes les personnes int\u00e9ress\u00e9es. Si le poste de membre du Conseil d\u2019administration de la Soci\u00e9t\u00e9 d\u2019aide au d\u00e9veloppement des collectivit\u00e9s Sup\u00e9rieur Est vous int\u00e9resse, veuillez envoyer une lettre d\u00e9crivent vos qualit\u00e9s et un bref curriculum vitae pour examen par le conseil \u00e0 Tracy Amos \u00e0 amos@superioreastcfdc.ca.<\/p>\n<p>Pour obtenir plus d\u2019information sur les activit\u00e9s de la SADC, veuillez vous adresser \u00e0 notre bureau au 705-856-1105 ou par courriel amos@superioreastcfdc.on.ca ou visitez notre site Internet \u00e0 www.superioreastcfdc.ca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Soci\u00e9t\u00e9 d\u2019aide au d\u00e9veloppement des collectivit\u00e9s Sup\u00e9rieur Est cherche membre du conseil d\u2019administration La Soci\u00e9t\u00e9 d\u2019aide au d\u00e9veloppement des collectivit\u00e9s du Sup\u00e9rieur Est (SADCSE) a des postes \u00e0 combler sur son conseil d\u2019administration pour la r\u00e9gion de Wawa. La SADC est une soci\u00e9t\u00e9 \u00e0 but non-lucratif offrant des services r\u00e9gionaux de d\u00e9veloppement \u00e9conomique et &#8230;<\/p>\n","protected":false},"author":50,"featured_media":57692,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1765],"tags":[],"class_list":["post-58372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ad-text"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:19:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/58372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/comments?post=58372"}],"version-history":[{"count":1,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/58372\/revisions"}],"predecessor-version":[{"id":58373,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/58372\/revisions\/58373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media\/57692"}],"wp:attachment":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media?parent=58372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/categories?post=58372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/tags?post=58372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}