{"id":48347,"date":"2021-10-27T08:29:34","date_gmt":"2021-10-27T12:29:34","guid":{"rendered":"https:\/\/wawa-news.com\/?p=48347"},"modified":"2021-10-27T08:31:05","modified_gmt":"2021-10-27T12:31:05","slug":"apprendre-les-mathematiques-grace-aux-hippopotames-affames","status":"publish","type":"post","link":"https:\/\/wawa-news.com\/index.php\/2021\/10\/27\/apprendre-les-mathematiques-grace-aux-hippopotames-affames\/","title":{"rendered":"Apprendre les math\u00e9matiques gr\u00e2ce aux hippopotames affam\u00e9s"},"content":{"rendered":"<p><a href=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/10\/Screen-Shot-2021-10-27-at-8.25.42-AM-e1635337719862.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-48344\" src=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/10\/Screen-Shot-2021-10-27-at-8.25.42-AM-600x441.png\" alt=\"\" width=\"600\" height=\"441\" \/><\/a><\/p>\n<p><a href=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/10\/Screen-Shot-2021-10-27-at-8.25.25-AM-e1635337704722.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-48345\" src=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/10\/Screen-Shot-2021-10-27-at-8.25.25-AM-300x196.png\" alt=\"\" width=\"300\" height=\"196\" \/><\/a>Quand M<sup>me<\/sup> Monique Grendron, enseignante \u00e0 l\u2019\u00e9cole Saint-Joseph (Wawa), a premi\u00e8rement vu le jeu Hungry Hungry Hippos, elle savait qu\u2019elle devait l\u2019int\u00e9grer, d\u2019une fa\u00e7on ou d\u2019une autre, dans sa salle de classe. Motiv\u00e9e \u00e0 permettre aux \u00e9l\u00e8ves d\u2019apprendre en s\u2019amusant, elle a donc modifi\u00e9 la version originale de ce jeu d\u2019hippopotames affam\u00e9s afin de cr\u00e9er une version qui met de l\u2019avant les additions et les soustractions.<\/p>\n<p>&nbsp;<\/p>\n<p>Il s\u2019agit d\u2019une version du jeu que tous les \u00e9l\u00e8ves peuvent mettre en pratique. De plus, cet apprentissage par le jeu permet aux \u00e9l\u00e8ves de mieux comprendre et de revoir les principes d\u2019addition et de soustraction tout en travaillant en \u00e9quipes et en \u00e9laborant des strat\u00e9gies de r\u00e9solutions de probl\u00e8mes!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quand Mme Monique Grendron, enseignante \u00e0 l\u2019\u00e9cole Saint-Joseph (Wawa), a premi\u00e8rement vu le jeu Hungry Hungry Hippos, elle savait qu\u2019elle devait l\u2019int\u00e9grer, d\u2019une fa\u00e7on ou d\u2019une autre, dans sa salle de classe. Motiv\u00e9e \u00e0 permettre aux \u00e9l\u00e8ves d\u2019apprendre en s\u2019amusant, elle a donc modifi\u00e9 la version originale de ce jeu d\u2019hippopotames affam\u00e9s afin de cr\u00e9er &#8230;<\/p>\n","protected":false},"author":3,"featured_media":48344,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[853],"class_list":["post-48347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-education","tag-ecole-saint-joseph-wawa"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 01:09:04","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/48347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/comments?post=48347"}],"version-history":[{"count":1,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/48347\/revisions"}],"predecessor-version":[{"id":48348,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/48347\/revisions\/48348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media\/48344"}],"wp:attachment":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media?parent=48347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/categories?post=48347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/tags?post=48347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}