{"id":48149,"date":"2021-10-19T08:00:10","date_gmt":"2021-10-19T12:00:10","guid":{"rendered":"https:\/\/wawa-news.com\/?p=48149"},"modified":"2021-10-19T06:38:13","modified_gmt":"2021-10-19T10:38:13","slug":"lontario-investit-plus-de-25-millions-de-dollars-pour-proteger-les-grands-lacs","status":"publish","type":"post","link":"https:\/\/wawa-news.com\/index.php\/2021\/10\/19\/lontario-investit-plus-de-25-millions-de-dollars-pour-proteger-les-grands-lacs\/","title":{"rendered":"L\u2019Ontario investit plus de 2,5 millions de dollars pour prot\u00e9ger les Grands Lacs"},"content":{"rendered":"<div>\n<p>Le gouvernement de l\u2019Ontario investit plus de 2,5 millions de dollars dans 19 nouveaux projets pour prot\u00e9ger la sant\u00e9 des Grands Lacs dans le cadre de l\u2019engagement qu\u2019il a pris lors de la signature r\u00e9cente de l\u2019Accord Canada-Ontario sur la qualit\u00e9 de l\u2019eau et la sant\u00e9 de l\u2019\u00e9cosyst\u00e8me des Grands Lacs. Ces projets contribueront \u00e0 am\u00e9liorer la qualit\u00e9 de l\u2019eau du plus vaste r\u00e9seau de lacs d\u2019eau douce au monde en aidant les agriculteurs et les propri\u00e9taires fonciers \u00e0 r\u00e9aliser des projets d\u2019infrastructures vertes et \u00e0 adopter les meilleures pratiques qui am\u00e9lioreront l\u2019efficience et la viabilit\u00e9 de leurs activit\u00e9s tout en r\u00e9duisant la quantit\u00e9 de contaminants et d\u2019\u00e9l\u00e9ments nutritifs, comme les quantit\u00e9s excessives de phosphore, qui se d\u00e9versent dans les Grands Lacs.<\/p>\n<\/div>\n<div>\n<p>\u00ab Notre gouvernement est fier de tenir son engagement de prot\u00e9ger, de conserver et de restaurer les Grands Lacs, a d\u00e9clar\u00e9 David Piccini, ministre de l\u2019Environnement, de la Protection de la nature et des Parcs. Dans le bassin des Grands Lacs se trouvent 95 pour 100 des terres agricoles de l\u2019Ontario. C\u2019est pourquoi il est si important d\u2019investir dans des projets qui permettront \u00e0 nos partenaires agricoles d\u2019adopter les meilleures pratiques et les innovations les plus r\u00e9centes, et de maintenir les cours d\u2019eau locaux propres et en bonne sant\u00e9. Ces 19 initiatives auront un impact positif sur les Grands Lacs, leurs bassins versants et le bien-\u00eatre des communaut\u00e9s qui en d\u00e9pendent tous les jours. \u00bb<\/p>\n<p>David Piccini, ministre de l\u2019Environnement, de la Protection de la nature et des Parcs, \u00e9tait accompagn\u00e9 aujourd\u2019hui de Lisa Thompson, ministre de l\u2019Agriculture, de l\u2019Alimentation et des Affaires rurales, et de repr\u00e9sentants du Pine River Watershed Initiative Network pour annoncer les projets financ\u00e9s, qui comprennent les suivants :<\/p>\n<ul>\n<li>60 000 $ accord\u00e9s au Pine River Watershed Initiative Network pour sensibiliser, former et conseiller les agriculteurs et les propri\u00e9taires fonciers locaux afin qu\u2019ils adoptent les meilleures pratiques agricoles comme la plantation pour r\u00e9duire l\u2019\u00e9rosion des sols et les ouvrages de franchissement de cours d\u2019eau pour le b\u00e9tail pour \u00e9viter le d\u00e9versement de fumier dans l\u2019eau.<\/li>\n<li>300 000 $ accord\u00e9s \u00e0 l\u2019Office de protection de la nature d\u2019Ausable Bayfield pour aider les agriculteurs \u00e0 g\u00e9rer les sols et \u00e0 produire des cultures, ainsi que pour \u00e9laborer une strat\u00e9gie ayant pour but de rep\u00e9rer les risques les plus graves et les possibilit\u00e9s en lien avec les meilleures pratiques de gestion et les infrastructures vertes.<\/li>\n<li>199 800 $ accord\u00e9s \u00e0 l\u2019Universit\u00e9 Ryerson pour \u00e9valuer la fa\u00e7on dont les pratiques agricoles peuvent r\u00e9duire les quantit\u00e9s d\u2019\u00e9l\u00e9ments nutritifs d\u00e9vers\u00e9s dans les rivi\u00e8res qui se jettent dans les Grands Lacs et affectent la qualit\u00e9 de l\u2019eau.<\/li>\n<li>265 000 $ accord\u00e9s \u00e0 l\u2019Association pour l\u2019am\u00e9lioration des sols et des r\u00e9coltes de l\u2019Ontario pour mettre au point une technologie mobile d\u2019\u00e9valuation de la sant\u00e9 des sols permettant aux experts de la sant\u00e9 des sols de d\u00e9montrer les effets du compactage des sols sur leur sant\u00e9.<\/li>\n<\/ul>\n<p>Ces projets s\u2019inscrivent dans le cadre du Programme LEADS pour une agriculture durable dans la r\u00e9gion du lac \u00c9ri\u00e9, un projet de cinq ans dot\u00e9 d\u2019un budget de 15,6 millions de dollars r\u00e9alis\u00e9 conjointement par les gouvernements f\u00e9d\u00e9ral et provincial par l\u2019entremise du Partenariat canadien pour l\u2019agriculture pour aider les agriculteurs \u00e0 prot\u00e9ger les lacs et les sources d\u2019eau en adoptant des pratiques agricoles plus viables, qui auront \u00e9galement pour effet de rendre les activit\u00e9s agricoles plus r\u00e9silientes.<\/p>\n<p>\u00ab Les agriculteurs ontariens travaillent sans rel\u00e2che pour prot\u00e9ger l\u2019environnement en utilisant les meilleures pratiques de gestion agricole, a d\u00e9clar\u00e9 Lisa Thompson, ministre de l\u2019Agriculture, de l\u2019Alimentation et des Affaires rurales. En accordant des fonds aux agriculteurs de la province pour qu\u2019ils mettent en \u0153uvre les plus r\u00e9centes pratiques agricoles viables, nous les aidons \u00e0 prot\u00e9ger les lacs et les cours d\u2019eau, ainsi qu\u2019\u00e0 am\u00e9liorer la sant\u00e9 des sols. \u00bb<\/p>\n<p>\u00ab Nous remercions le gouvernement de nous accorder un soutien et de nous donner l\u2019occasion de faire conna\u00eetre les initiatives et les programmes importants que le Pine River Watershed Initiative Network continue de mettre en \u0153uvre pour am\u00e9liorer la qualit\u00e9 de l\u2019eau du lac Huron et du bassin versant de la rivi\u00e8re Pine \u00e0 l\u2019\u00e9chelle locale \u00bb, a d\u00e9clar\u00e9 Donald Farrell, directeur du Pine River Watershed Initiative Network.<\/p>\n<p>Le financement accord\u00e9 aux 19 projets s\u2019inscrit dans le cadre de l\u2019investissement pluriannuel de 10,9 millions de dollars de l\u2019Ontario ayant pour but de soutenir les projets r\u00e9alis\u00e9s par les offices de protection de la nature, les organismes environnementaux sans but lucratif, les universit\u00e9s et les organismes autochtones partout dans la province pour respecter les engagements pris en vertu de l\u2019Accord Canada-Ontario sur les Grands Lacs.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le gouvernement de l\u2019Ontario investit plus de 2,5 millions de dollars dans 19 nouveaux projets pour prot\u00e9ger la sant\u00e9 des Grands Lacs dans le cadre de l\u2019engagement qu\u2019il a pris lors de la signature r\u00e9cente de l\u2019Accord Canada-Ontario sur la qualit\u00e9 de l\u2019eau et la sant\u00e9 de l\u2019\u00e9cosyst\u00e8me des Grands Lacs. Ces projets contribueront \u00e0 &#8230;<\/p>\n","protected":false},"author":46,"featured_media":31649,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-48149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-weather"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 18:53:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/48149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/comments?post=48149"}],"version-history":[{"count":1,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/48149\/revisions"}],"predecessor-version":[{"id":48150,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/48149\/revisions\/48150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media\/31649"}],"wp:attachment":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media?parent=48149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/categories?post=48149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/tags?post=48149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}