{"id":40846,"date":"2021-01-05T08:44:06","date_gmt":"2021-01-05T13:44:06","guid":{"rendered":"https:\/\/wawa-news.com\/?p=40846"},"modified":"2021-01-05T08:44:35","modified_gmt":"2021-01-05T13:44:35","slug":"un-apprentissage-stimulant-a-lesc-trillium","status":"publish","type":"post","link":"https:\/\/wawa-news.com\/index.php\/2021\/01\/05\/un-apprentissage-stimulant-a-lesc-trillium\/","title":{"rendered":"Un apprentissage stimulant \u00e0 l\u2019\u00c9SC Trillium"},"content":{"rendered":"<table class=\"tg\">\n<thead>\n<tr>\n<th class=\"tg-0pky\"><a href=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-40842\" src=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-1-300x225.jpg 300w, https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-1-600x450.jpg 600w, https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-1-768x576.jpg 768w, https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/th>\n<th class=\"tg-0pky\"><a href=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-40844\" src=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-2-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-2-300x225.jpg 300w, https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-2-600x450.jpg 600w, https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-2-768x576.jpg 768w, https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-2.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/th>\n<\/tr>\n<\/thead>\n<\/table>\n<p><a href=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-40843\" src=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-3-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-3-300x225.jpg 300w, https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-3-600x450.jpg 600w, https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-3-768x576.jpg 768w, https:\/\/wawa-news.com\/wp-content\/uploads\/2021\/01\/pig-3.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Avant le cong\u00e9 de No\u00ebl, les \u00e9l\u00e8ves de l\u2019\u00e9cole secondaire catholique Trillium (Chapleau) ont pu concr\u00e9tiser leur apprentissage dans le laboratoire de sciences de l\u2019\u00e9cole. Dans le cours de biologie, ils ont fait la dissection d\u2019un cochon afin d\u2019\u00e9tudier la structure, les fonctions et les processus internes des divers syst\u00e8mes de l\u2019animal.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avant le cong\u00e9 de No\u00ebl, les \u00e9l\u00e8ves de l\u2019\u00e9cole secondaire catholique Trillium (Chapleau) ont pu concr\u00e9tiser leur apprentissage dans le laboratoire de sciences de l\u2019\u00e9cole. Dans le cours de biologie, ils ont fait la dissection d\u2019un cochon afin d\u2019\u00e9tudier la structure, les fonctions et les processus internes des divers syst\u00e8mes de l\u2019animal. &nbsp;<\/p>\n","protected":false},"author":3,"featured_media":40844,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":["post-40846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-education"],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:26:57","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/40846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/comments?post=40846"}],"version-history":[{"count":1,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/40846\/revisions"}],"predecessor-version":[{"id":40847,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/40846\/revisions\/40847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media\/40844"}],"wp:attachment":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media?parent=40846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/categories?post=40846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/tags?post=40846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}