{"id":35044,"date":"2020-08-02T09:06:33","date_gmt":"2020-08-02T13:06:33","guid":{"rendered":"https:\/\/wawa-news.com\/?p=35044"},"modified":"2020-08-02T09:07:40","modified_gmt":"2020-08-02T13:07:40","slug":"le-gouvernement-de-lontario-encourage-tous-les-residents-et-residentes-a-relever-le-defi-30x30-de-parcs-ontario","status":"publish","type":"post","link":"https:\/\/wawa-news.com\/index.php\/2020\/08\/02\/le-gouvernement-de-lontario-encourage-tous-les-residents-et-residentes-a-relever-le-defi-30x30-de-parcs-ontario\/","title":{"rendered":"Le gouvernement de l&#8217;Ontario encourage tous les r\u00e9sidents et r\u00e9sidentes \u00e0 relever le D\u00e9fi 30&#215;30 de Parcs Ontario"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-35042\" src=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2020\/08\/30x30-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2020\/08\/30x30-300x200.jpg 300w, https:\/\/wawa-news.com\/wp-content\/uploads\/2020\/08\/30x30-150x100.jpg 150w, https:\/\/wawa-news.com\/wp-content\/uploads\/2020\/08\/30x30-500x333.jpg 500w, https:\/\/wawa-news.com\/wp-content\/uploads\/2020\/08\/30x30.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Le ministre de l&#8217;Environnement, de la Protection de la nature et des Parcs, Jeff Yurek, a publi\u00e9 la d\u00e9claration suivante \u00e0 l&#8217;intention de tous les Ontariens et Ontariennes\u00a0:<\/p>\n<p>\u00ab Depuis des mois, les particuliers et les familles font leur part pour freiner la propagation de la COVID-19 en restant chez eux, et je voudrais souligner leur effort. Gr\u00e2ce aux progr\u00e8s que nous avons accomplis ensemble, et alors que nous passons \u00e0 la 3e \u00e9tape du d\u00e9confinement de la province, j&#8217;encourage toutes les personnes, quels que soient leur \u00e2ge et leur milieu, \u00e0 passer du temps \u00e0 l&#8217;ext\u00e9rieur et \u00e0 profiter en toute s\u00e9curit\u00e9 du magnifique \u00e9t\u00e9 ontarien.<\/p>\n<p>Si vous cherchez une bonne raison de sortir, vous pouvez relever le <a href=\"http:\/\/www.ontarioparks.com\/hphp\/challenge\/fr\">D\u00e9fi 30&#215;30<\/a> de Parcs Ontario. Ce d\u00e9fi annuel, qui dure tout le mois d&#8217;ao\u00fbt, est organis\u00e9 dans le cadre de l&#8217;initiative <a href=\"http:\/\/www.ontarioparks.com\/hphp\/fr\">Sant\u00e9 des parcs, sant\u00e9 des populations<\/a> de notre gouvernement. Le D\u00e9fi 30&#215;30 consiste pour les participants \u00e0 passer 30 minutes dans la nature tous les jours pendant 30 jours.<\/p>\n<p>Le D\u00e9fi 30&#215;30 est une excellente fa\u00e7on de prendre, ou de reprendre, des habitudes saines qui auront un impact positif sur notre vie pour des ann\u00e9es \u00e0 venir. On sait que passer du temps dans la nature a un impact profond sur la sant\u00e9 et le bien-\u00eatre, est b\u00e9n\u00e9fique pour l&#8217;humeur, renforce le syst\u00e8me immunitaire et r\u00e9duit le stress. Il y a de nombreuses fa\u00e7ons de participer, comme partir en randonn\u00e9e \u00e0 v\u00e9lo, faire une longue promenade \u00e0 pied ou explorer des espaces verts, comme un parc provincial.<\/p>\n<p>Bien que les gens soient encourag\u00e9s \u00e0 \u00eatre plus actifs, il est important de se rappeler que nous devons \u00eatre responsables et continuer de suivre les conseils de sant\u00e9 publique, y compris garder nos distances avec les autres \u00e0 l&#8217;int\u00e9rieur comme \u00e0 l&#8217;ext\u00e9rieur, porter un masque quand on ne peut garder ses distances ou que c&#8217;est exig\u00e9, se laver les mains fr\u00e9quemment et \u00e9viter les grands rassemblements. \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le ministre de l&#8217;Environnement, de la Protection de la nature et des Parcs, Jeff Yurek, a publi\u00e9 la d\u00e9claration suivante \u00e0 l&#8217;intention de tous les Ontariens et Ontariennes\u00a0: \u00ab Depuis des mois, les particuliers et les familles font leur part pour freiner la propagation de la COVID-19 en restant chez eux, et je voudrais souligner &#8230;<\/p>\n","protected":false},"author":47,"featured_media":35042,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-35044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincial"],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 23:09:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/35044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/comments?post=35044"}],"version-history":[{"count":1,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/35044\/revisions"}],"predecessor-version":[{"id":35045,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/35044\/revisions\/35045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media\/35042"}],"wp:attachment":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media?parent=35044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/categories?post=35044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/tags?post=35044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}