{"id":19694,"date":"2019-03-06T08:03:32","date_gmt":"2019-03-06T13:03:32","guid":{"rendered":"https:\/\/wawa-news.com\/?p=19694"},"modified":"2019-03-06T04:51:23","modified_gmt":"2019-03-06T09:51:23","slug":"recital-de-piano-a-lecole-saint-joseph","status":"publish","type":"post","link":"https:\/\/wawa-news.com\/index.php\/2019\/03\/06\/recital-de-piano-a-lecole-saint-joseph\/","title":{"rendered":"R\u00e9cital de piano \u00e0 l\u2019\u00e9cole Saint-Joseph"},"content":{"rendered":"<p><a href=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2019\/03\/piano-0004.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-19692\" src=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2019\/03\/piano-0004-600x400.jpg\" alt=\"\" width=\"600\" height=\"400\" srcset=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2019\/03\/piano-0004.jpg 600w, https:\/\/wawa-news.com\/wp-content\/uploads\/2019\/03\/piano-0004-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2019\/03\/piano-0009.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-19691\" src=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2019\/03\/piano-0009-300x240.jpg\" alt=\"\" width=\"300\" height=\"240\" srcset=\"https:\/\/wawa-news.com\/wp-content\/uploads\/2019\/03\/piano-0009-300x240.jpg 300w, https:\/\/wawa-news.com\/wp-content\/uploads\/2019\/03\/piano-0009.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Depuis le mois d\u2019octobre, Matthew Schumacher, \u00e9l\u00e8ve COOP \u00e0 l\u2019\u00c9cole secondaire Saint-Joseph, Wawa, offre des cours de piano gratuits aux \u00e9l\u00e8ves de la 1<sup>re<\/sup>, 2<sup>e<\/sup> et 3<sup>e<\/sup> ann\u00e9e. Sous les directives de ce jeune pianiste accompli, les \u00e9l\u00e8ves ont appris \u00e0 lire les notes et \u00e0 jouer avec harmonie. Pour cl\u00f4turer le semestre et mettre \u00e0 l\u2019honneur l\u2019accomplissement de ses \u00e9l\u00e8ves, Matthew a organis\u00e9 un r\u00e9cital de piano le mercredi 13 f\u00e9vrier. Parents et amis ont pu assister \u00e0 ce r\u00e9cital o\u00f9 chaque \u00e9l\u00e8ve jouait une chanson unique de son choix!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Depuis le mois d\u2019octobre, Matthew Schumacher, \u00e9l\u00e8ve COOP \u00e0 l\u2019\u00c9cole secondaire Saint-Joseph, Wawa, offre des cours de piano gratuits aux \u00e9l\u00e8ves de la 1re, 2e et 3e ann\u00e9e. Sous les directives de ce jeune pianiste accompli, les \u00e9l\u00e8ves ont appris \u00e0 lire les notes et \u00e0 jouer avec harmonie. Pour cl\u00f4turer le semestre et &#8230;<\/p>\n","protected":false},"author":3,"featured_media":19691,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":["post-19694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-education"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 15:16:35","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/19694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/comments?post=19694"}],"version-history":[{"count":1,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/19694\/revisions"}],"predecessor-version":[{"id":19695,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/posts\/19694\/revisions\/19695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media\/19691"}],"wp:attachment":[{"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/media?parent=19694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/categories?post=19694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wawa-news.com\/index.php\/wp-json\/wp\/v2\/tags?post=19694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}